{"id":2881,"date":"2013-07-17T17:25:24","date_gmt":"2013-07-17T15:25:24","guid":{"rendered":"https:\/\/www.galde.eu\/?p=2881"},"modified":"2025-10-23T18:17:19","modified_gmt":"2025-10-23T16:17:19","slug":"los-espacios-publicos-para-quien-los-frecuenta","status":"publish","type":"post","link":"https:\/\/www.galde.eu\/eu\/los-espacios-publicos-para-quien-los-frecuenta\/","title":{"rendered":"Los espacios p\u00fablicos, para quien los frecuenta"},"content":{"rendered":"<p><\/p>\n<div>\n<dl id=\"attachment_2882\">\n<dt><a href=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2014\/06\/munduarrozak1.jpg\"><img class=\"colorbox-2881\"  loading=\"lazy\" decoding=\"async\" alt=\"munduko arrozak - arroces del mundo\" src=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2014\/06\/munduarrozak1.jpg\" width=\"443\" height=\"363\" data-id=\"2882\" \/><\/a><\/dt>\n<dd>Encuentro multicultural de Munduko Arrozak &#8211; Arroces del Mundo.<\/dd>\n<\/dl>\n<\/div>\n<p>(Galde 02, primavera\/2013). \u00a0No hay pretensi\u00f3n cient\u00edfica, solo observaci\u00f3n de campo circunscrita a mi entorno vital, que con lo micro cabalgamos. Las familias de hace cuarenta a\u00f1os, corr\u00edjanme, sal\u00edan los festivos a la periferia urbana y ocupaban ruidosamente riberas y pastizales. Las administraciones p\u00fablicas atendieron ese h\u00e1bito con arbolados y asadores p\u00fablicos. En alg\u00fan momento de la posmodernidad cayeron en desuso, incluso para las pandillas juveniles, y as\u00ed permanecieron hasta que los inmigrantes las han recuperado. Basta que la lluvia amaine para que latinoamericanos de todo sexo y edad asen carnes, jueguen al voley y propaguen la bachata. En medio del asombro y la envidia de los nacionales, de todos los nacionales, que ya andar\u00e1n buscando excusas para quitarlos de la vista. No s\u00e9 si mezclan por nacionalidades ni si aceptan comensales de otras etnias. Nos lo resolver\u00e1n los multiculturalistas. Por ahora, baste el humanista:<\/p>\n<p>&#8220;El peque\u00f1o autom\u00f3vil avanzaba en paralelo al Kings River, cerca de la zona de picnics. Aquel domingo por la tarde se celebraban cinco grandes picnics, con m\u00fasica y bailes: uno italiano, otro griego, otro serbio, otro armenio y otro norteamericano. Cada grupo ten\u00eda su propio estilo de m\u00fasica y baile (&#8230;). El autom\u00f3vil lleg\u00f3 al \u00faltimo grupo. La m\u00fasica era swing, jive y boogie-woogie, y el baile era desenfrenado.<\/p>\n<p>-\u00a1Norteamericanos! Griegos, serbios, polacos, rusos, mexicanos, armenios, alemanes, negros, suecos, espa\u00f1oles, vascos, portugueses, italianos, jud\u00edos, franceses, ingleses, escoceses, irlandeses. Lo que t\u00fa quieras. Eso es lo que somos.<br \/>\nWilliam Saroyan,\u00a0<i>La comedia humana<\/i>\u00a0(1943)&#8221;<\/p>\n<p>Soledad Fr\u00edas<\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Ez dago.<\/p>\n","protected":false},"author":2,"featured_media":2884,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,12],"tags":[],"class_list":["post-2881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-miradas","revista-galde-2"],"_links":{"self":[{"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/posts\/2881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/comments?post=2881"}],"version-history":[{"count":1,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/posts\/2881\/revisions"}],"predecessor-version":[{"id":18775,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/posts\/2881\/revisions\/18775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/media\/2884"}],"wp:attachment":[{"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/media?parent=2881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/categories?post=2881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/tags?post=2881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}