{"id":11184,"date":"2019-03-20T11:20:03","date_gmt":"2019-03-20T10:20:03","guid":{"rendered":"https:\/\/www.galde.eu\/?p=11184"},"modified":"2019-04-05T13:06:48","modified_gmt":"2019-04-05T11:06:48","slug":"green-new-deal-que-es-como-puede-funcionar","status":"publish","type":"post","link":"https:\/\/www.galde.eu\/eu\/green-new-deal-que-es-como-puede-funcionar\/","title":{"rendered":"Green New Deal: \u00bfqu\u00e9 es? \u00bfc\u00f3mo puede funcionar?"},"content":{"rendered":"<p><a href=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2019\/03\/GreenNID1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11188 colorbox-11184\" src=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2019\/03\/GreenNID1.jpg\" alt=\"\" width=\"580\" height=\"326\" data-id=\"11188\" srcset=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2019\/03\/GreenNID1.jpg 580w, https:\/\/www.galde.eu\/wp-content\/uploads\/2019\/03\/GreenNID1-300x169.jpg 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Galde 24, (udaberria\/2019\/primavera).\u00a0Jeremy Brecher.-<span class=\"s1\"> <a class=\"simple-footnote\" title=\"Jeremy Brecher es historiador, cineasta, y cofundador de Labor Network for Sustainability.\" id=\"return-note-11184-1\" href=\"#note-11184-1\"><sup>1<\/sup><\/a><\/p>\n<p><em>A semejanza de lo que fue el New Deal impulsado por la administraci\u00f3n Roosevelt en los a\u00f1os 30, el Green New Deal (GND) (Nuevo Pacto Verde en espa\u00f1ol) -presentado recientemente por la congresista Alexandra Ocasio-Cortez (D-NY) y el senador Ed Markey (D-Mass.)- representa la propuesta con la que el Partido Dem\u00f3crata pretende hacer frente a la crisis econ\u00f3mica y enfrentar al mismo tiempo la amenaza del cambio clim\u00e1tico. Desde Galde hemos querido acercarnos a esta propuesta y darla a conocer, resumiendo para ello un texto publicado recientemente en diversos medios digitales por Jeremy Brecher.<\/em><\/p>\n<p><strong>Movilizar al gobierno<\/strong><\/p>\n<p>El calentamiento global se ha llamado, con raz\u00f3n, el &#8220;mayor fracaso del mercado&#8221; en la historia. Por tanto, corregirlo no se puede confiar al mercado. El GND necesitar\u00e1 una planificaci\u00f3n econ\u00f3mica audaz, as\u00ed como pol\u00edticas industriales e inversi\u00f3n p\u00fablica para guiar y facilitar el proceso. Necesitar\u00e1 tambi\u00e9n pol\u00edticas macroecon\u00f3micas de pleno empleo, que aseguren la prosperidad y fomenten un uso eficiente de los recursos econ\u00f3micos durante la transici\u00f3n. Y necesitar\u00e1 la movilizaci\u00f3n p\u00fablica y la redirecci\u00f3n de los recursos humanos y materiales que se requieren para esa transici\u00f3n. En definitiva, el GND requiere instituciones gubernamentales espec\u00edficamente dise\u00f1adas para implementar la transici\u00f3n hacia la protecci\u00f3n del clima.<\/p>\n<p><strong>Establecer agencias gubernamentales para supervisar la transici\u00f3n<\/strong><\/p>\n<p>La movilizaci\u00f3n para el GND es una emergencia. Por ello, las agencias del Green New Deal, establecidas por el Congreso, recaudar\u00e1n capital, desarrollar\u00e1n estrategias de creaci\u00f3n de empleo, organizar\u00e1n el financiamiento para infraestructuras,financiar\u00e1n la investigaci\u00f3n y el desarrollo, establecer\u00e1n y controlar\u00e1n los est\u00e1ndares de eficiencia energ\u00e9tica para edificios, electrodom\u00e9sticos y equipos, capacitar\u00e1n continuamente a trabajadores y profesionales, establecer\u00e1n pol\u00edticas de ubicaci\u00f3n industrial, y coordinar\u00e1n las actividades multifac\u00e9ticas de agencias federales, gobiernos estatales y municipales, corporaciones y organizaciones de la sociedad civil. La iniciativa del gobierno es necesaria para eliminar la inercia, los cuellos de botella y la burocracia. La protecci\u00f3n del clima requiere la capacidad de hacer planes a largo plazo que afecten muchos aspectos de la vida. Requiere tomar decisiones, as\u00ed como capacidad t\u00e9cnica para dise\u00f1ar y desarrollar tales sistemas complejos. Requiere asimismo tener en cuenta una amplia gama de factores econ\u00f3micos, ambientales y sociales, maximizando los efectos secundarios beneficiosos y minimizando los no deseados.<\/p>\n<p><strong>Usar los poderes de regulaci\u00f3n para congelar, eliminar gradualmente y reemplazar toda la infraestructura de combustibles f\u00f3siles<\/strong><\/p>\n<p>En 1942, el presidente Franklin Roosevelt prohibi\u00f3 la producci\u00f3n de autom\u00f3viles de pasajeros para permitir la reorganizaci\u00f3n de la industria para la producci\u00f3n de guerra. Los objetivos del GND requieren una disminuci\u00f3n similar, aunque m\u00e1s gradual, en la producci\u00f3n y el uso de combustibles f\u00f3siles y su reemplazo por otras fuentes de energ\u00eda. Tal transici\u00f3n debe ser ejecutada por los poderes regulatorios gubernamentales. Los est\u00e1ndares estatales de cartera renovable (RPS) proporcionan un ejemplo. Un RPS nacional debe requerir el reemplazo de energ\u00eda de combustibles f\u00f3siles por energ\u00eda renovable seg\u00fan la tasa anual necesaria para cumplir con los objetivos del GND. Se deben desarrollar est\u00e1ndares similares para la conversi\u00f3n del transporte, edificios, industria y todos los dem\u00e1s sectores productores de Gases de Efecto Invernadero (GEI).<\/p>\n<p><strong>Establecer agencias del Green New Deal para reorganizar los sectores econ\u00f3micos<\/strong><\/p>\n<p>Una econom\u00eda libre de f\u00f3siles requerir\u00e1 la transformaci\u00f3n no solo de los lugares de trabajo, de cada empresa y de la econom\u00eda en general, sino de industrias y sectores econ\u00f3micos espec\u00edficos. La planificaci\u00f3n en la industria es necesaria para generar sinergias y econom\u00edas de escala, establecer \u00e1reas equilibradas de actuaci\u00f3n y garantizar que las diferentes partes de un sistema emergente de protecci\u00f3n del clima trabajen juntas, con una coordinaci\u00f3n a gran escala y a largo plazo que no puede ser ejercida por el mercado. Las pol\u00edticas p\u00fablicas sobre el clima, la negociaci\u00f3n colectiva en toda la industria y la cooperaci\u00f3n entre empresas en la misma industria deben ir de la mano.<\/p>\n<p>Un buen ejemplo de esa cooperaci\u00f3n fue la reconstrucci\u00f3n de la industria automotriz de los Estados Unidos bajo el plan de recuperaci\u00f3n econ\u00f3mica del Presidente Obama. Las corporaciones del autom\u00f3vil y el Sindicato de Trabajadores del Autom\u00f3vil (UAW) acordaron un gran aumento a largo plazo de la eficiencia energ\u00e9tica para reducir las emisiones de carbono. El resultado fue una disminuci\u00f3n constante en las tasas de contaminaci\u00f3n, un aumento en los empleos para los trabajadores del autom\u00f3vil, y el fin de la crisis que amenazaba con eliminar casi la producci\u00f3n de autom\u00f3viles en los Estados Unidos.Programas sectoriales similares se necesitan en electricidad, transporte, agricultura, silvicultura, manufactura, manejo de desechos, finanzas y muchas otras industrias.<\/p>\n<p><strong>Utilizar las herramientas de pol\u00edtica macroecon\u00f3mica<\/strong><\/p>\n<p>En los a\u00f1os 30, el New Deal utiliz\u00f3 las herramientas de la planificaci\u00f3n macroecon\u00f3mica para dirigir la econom\u00eda en su conjunto. Para combatir el desempleo y apoyar los programas del New Deal, se utiliz\u00f3 la pol\u00edtica fiscal, con d\u00e9ficits presupuestarios, y la pol\u00edtica monetaria, con bajas tasas de inter\u00e9s. Si bien el neoliberalismo conden\u00f3 las pol\u00edticas macroecon\u00f3micas keynesianas dise\u00f1adas para proporcionar el pleno empleo, el abandono de tal direcci\u00f3n condujo a la crisis econ\u00f3mica m\u00e1s profunda desde la Gran Depresi\u00f3n, a una creciente polarizaci\u00f3n de los ingresos y a un mayor empobrecimiento de los trabajadores. El GND debe aplicar pol\u00edticas macroecon\u00f3micas que aseguren el pleno empleo para reducir el temor de que la protecci\u00f3n del clima pueda amenazar la prosperidad, y tambi\u00e9n para dar a los trabajadores una mayor participaci\u00f3n en la transici\u00f3n.<\/p>\n<p><strong>Usar los poderes del gobierno para rectificar injusticias pasadas y presentes<\/strong><\/p>\n<p>Los trabajos que protegen el clima deben ponerse a disposici\u00f3n de aquellas personas con dificultades para acceder a buenos empleos. Debe efectuarse una discriminaci\u00f3n positiva que tenga en cuenta raza, g\u00e9nero, edad y ubicaci\u00f3n para contrarrestar nuestras desigualdades laborales actuales. Los programas requerir\u00e1n est\u00e1ndares para la contrataci\u00f3n local y para las empresas comerciales minoritarias. Asimismo, los proyectos del GND deber\u00e1n reducir la concentraci\u00f3n de la contaminaci\u00f3n en comunidades marginadas y de bajos ingresos y contrarrestar\u00e1n la falta de transporte, educaci\u00f3n, salud y otros servicios en los vecindarios pobres.<\/p>\n<p><strong>Proteger a los consumidores de energ\u00eda de bajos ingresos <\/strong><\/p>\n<p>Los costos actuales de energ\u00eda de combustibles f\u00f3siles son en s\u00ed mismos una fuente importante de pobreza y desigualdad econ\u00f3mica. El GND debe garantizar que la factura energ\u00e9tica de las familias de bajos ingresos sea asequible, defini\u00e9ndola de manera general como el 6 por ciento de los ingresos brutos del hogar. La combinaci\u00f3n de inversiones en energ\u00eda solar, eficiencia y climatizaci\u00f3n reducir\u00e1 la cantidad de asistencia necesaria; en muchos casos, la factura estar\u00e1 por debajo del seis por ciento de los ingresos, eliminando la necesidad de asistencia. Todas las nuevas viviendas con bajos ingresos, p\u00fablicas o con subsidio p\u00fablico deber\u00e1n ser de <em>energ\u00eda neta cero <\/em>con paneles solares dentro y fuera de las mismas.<\/p>\n<p><strong>Potenciar las iniciativas lideradas por la comunidad<\/strong><\/p>\n<p>Hoy, una gran franja de programas comunitarios, locales y regionales ya est\u00e1n comprometidos en promover la transici\u00f3n a una econom\u00eda y sociedad con un clima saludable. Incluso en una transici\u00f3n dirigida por el gobierno, pueden, por iniciativa propia, implementar la producci\u00f3n de energ\u00eda renovable basada en la comunidad, como las placas solares en los techos, las medidas de reducci\u00f3n del uso de energ\u00eda como la climatizaci\u00f3n residencial, la movilizaci\u00f3n financiera a trav\u00e9s de fondos de inversi\u00f3n comunitarios y los nuevos patrones de consumo, como bicicletas compartidas. Quiz\u00e1s lo m\u00e1s importante es que pueden proporcionar tanto la participaci\u00f3n popular en la transici\u00f3n a la protecci\u00f3n del clima como los medios para controlar la responsabilidad de las instituciones de transici\u00f3n.<\/p>\n<p><strong>Democratizar la democracia<\/strong><\/p>\n<p>Las agencias del Green New Deal deben cumplir con el m\u00e1s alto nivel de transparencia y estar sujetas a los inspectores generales internos, a la Oficina de Contabilidad del Gobierno y a sus equivalentes especializados. Una agencia de supervisi\u00f3n independiente del poder ejecutivo, debe supervisar a las agencias e informar al Congreso y al p\u00fablico sobre su progreso, identificar problemas y fallas e iniciar las correcciones necesarias.El GND debe establecer est\u00e1ndares para los planes de acci\u00f3n sobre el clima, determinados democr\u00e1ticamente en todos los niveles, y similares a las declaraciones de impacto ambiental legalmente exigidas por muchas leyes sobre el medio ambiente. El GND debe alentar a los grupos de la comunidad local, las coaliciones y los gobiernos a desarrollar e implementar sus propios planes de acci\u00f3n sobre el clima a nivel comunitario y exigir dichos planes en todos los proyectos que se financian.<\/p>\n<p><strong>Movilizar a los trabajadores<\/strong><\/p>\n<p>Para movilizar el Green New Deal (GND) se requerir\u00e1n millones de trabajadores. Durante la Segunda Guerra Mundial, la Junta de Trabajo de Guerra reclut\u00f3 activamente trabajadores para las regiones e industrias donde m\u00e1s se necesitaban y el gobierno asumi\u00f3 el papel principal en la r\u00e1pida expansi\u00f3n de la educaci\u00f3n, la capacitaci\u00f3n, el cuidado infantil y la vivienda para la nueva fuerza laboral. Hoy en d\u00eda, una reserva laboral de m\u00e1s de 20 millones de personas desempleadas, subempleadas o fuera de la fuerza de trabajo podr\u00eda estar disponible para trabajar en la protecci\u00f3n del clima. El GND deber\u00e1 hacer coincidir a estos trabajadores con los sectores de empleo donde se necesitan y hacer coincidir los trabajos con las necesidades de los trabajadores.<\/p>\n<p><strong>No abandonar a nadie y garantizar empleos para todos<\/strong><\/p>\n<p>Si bien la protecci\u00f3n del clima producir\u00e1 muchos m\u00e1s empleos de los que elimina, tambi\u00e9n puede amenazar los de algunos trabajadores de las industrias que producen y utilizan combustibles f\u00f3siles. Es injusto que cualquier persona sufra las consecuencias de una pol\u00edtica que es necesaria para proteger a la sociedad. Por ello, el Green New Deal debe crear empleos y \/ o medios de vida alternativos para enfrentar el desempleo y evitar la oposici\u00f3n de algunos sectores a esas pol\u00edticas.<\/p>\n<p>La protecci\u00f3n de los trabajadores amenazados y de las comunidades que dependen de los empleos basados en combustibles f\u00f3siles debe plantearse antes de que comience la reestructuraci\u00f3n econ\u00f3mica. El Green New Deal deber\u00e1 crear nuevos fondos para reemplazar los impuestos y tarifas pagados por las instalaciones de combustibles f\u00f3siles e invertir en buenos empleos en las comunidades afectadas<\/p>\n<p><strong>Asegurar los derechos de los trabajadores y el empleo digno<\/strong><\/p>\n<p>El Green New Deal debe incluir est\u00e1ndares salariales que proporcionen una vida digna y un futuro para las familias trabajadoras. Debe respaldar las disposiciones salariales vigentes, como las exigidas por la Ley Davis-Bacon, y los acuerdos laborales de proyectos negociados entre los sindicatos y los empleadores, para garantizar que los empleos de protecci\u00f3n del clima mejoren, en lugar de reducir, los salarios y las condiciones laborales.<\/p>\n<p>El Green New Deal, como el New Deal original, debe establecer un nuevo marco que proteja los derechos humanos y constitucionales fundamentales de los trabajadores, reforzando los derechos a expresarse libremente, organizarse, negociar colectivamente y participar en acciones concertadas.<\/p>\n<p><strong>Movilizar dinero y recursos materiales<\/strong><\/p>\n<p>Cuando las personas oyen hablar sobre el Green New Deal, es probable que se pregunten &#8220;de d\u00f3nde vendr\u00e1 el dinero&#8221;. Temen que los costos sean enormes y que tengan que soportar esa carga a trav\u00e9s de impuestos m\u00e1s altos. Sin embargo, una econom\u00eda libre de combustibles f\u00f3siles ser\u00e1 mucho m\u00e1s barata que el modelo actual. Adem\u00e1s, se puede corregir nuestra extrema desigualdad mediante impuestos a los ricos para ayudar a pagar la protecci\u00f3n del clima. Hay que tener en cuenta asimismo los enormes recursos de la industria de combustibles f\u00f3siles que deber\u00edan ser usados \u200b\u200bpara pagar por el da\u00f1o que le han hecho a la tierra y a cada uno de sus habitantes. El GND podr\u00e1 utilizar los beneficios financieros de la energ\u00eda libre de f\u00f3siles, los billones de d\u00f3lares que se otorgan a las corporaciones y a los ricos en exenciones fiscales y subsidios, y la riqueza de la propia industria de combustibles f\u00f3siles para garantizar que los estadounidenses comunes se encuentren en mejores condiciones, como resultado de la transici\u00f3n a la seguridad en el clima.<\/p>\n<p><strong>Capturar los beneficios de la transici\u00f3n a la energ\u00eda libre de f\u00f3siles<\/strong><\/p>\n<p>La energ\u00eda libre de f\u00f3siles es ahora rentable: es m\u00e1s barata y ofrece m\u00e1s beneficios que la quema de combustibles f\u00f3siles. A largo plazo, la protecci\u00f3n del clima se pagar\u00e1 sola.<\/p>\n<p>En la actualidad, las grandes inversiones se destinan a mantener, reemplazar y ampliar la infraestructura de combustibles f\u00f3siles. El GND redirigir\u00e1 ese flujo de inversi\u00f3n para construir una econom\u00eda libre de f\u00f3siles, reemplazando los empleos de energ\u00eda perdidos y otros programas del GND. Del mismo modo, todo el dinero que se habr\u00eda gastado en carb\u00f3n, petr\u00f3leo y gas puede ir a los bolsillos de los consumidores y ayudar a pagar el GND.<\/p>\n<p><strong>Hacer pagar a los contaminadores<\/strong><\/p>\n<p>La industria de los combustibles f\u00f3siles puede y debe soportar gran parte de la carga por el da\u00f1o que causa a la humanidad y al planeta a trav\u00e9s de impuestos, tarifas, costos de permisos y otros cargos que pueden utilizarse para pagar el GND. La pol\u00edtica fiscal puede ayudar a desalentar las emisiones de carbono al tiempo que revierte nuestra creciente desigualdad de ingresos. Los impuestos progresivos, en particular sobre los bienes de lujo que producen cantidades ingentes de carbono como los jets privados, pueden contrarrestar los efectos negativos sobre la igualdad de ingresos. Otra fuente potencial para financiar la transici\u00f3n a la seguridad clim\u00e1tica pueden ser las sanciones legales y multas cobradas a las corporaciones por pr\u00e1cticas da\u00f1inas en el medio ambiente. El GND debe incluir legislaci\u00f3n para responsabilizar a los productores y emisores de combustibles f\u00f3siles por los da\u00f1os colosales infringidos a la atm\u00f3sfera, y el colosal costo de remediarlo.<\/p>\n<p><strong>Recortar gastos costosos e innecesarios<\/strong><\/p>\n<p>El gasto militar de los Estados Unidos equivale al de los siguientes siete pa\u00edses juntos. Aparte del despilfarro que ello supone, ha servido para apoyar una serie de guerras, muchas de ellas ilegales seg\u00fan las leyes nacionales e internacionales, ninguna de las cuales ha tenido \u00e9xito, causando un da\u00f1o humano y material incalculable y sin que ninguna haya contribuido a la seguridad del pueblo estadounidense. Muchas de estas guerras han sido motivadas por la b\u00fasqueda de combustibles f\u00f3siles y todas han contribuido al calentamiento global. Enfrentar el cambio clim\u00e1tico reducir\u00e1 los conflictos y promover\u00e1 la paz y la seguridad mundiales. La transferencia de fondos del presupuesto militar al GND mejorar\u00eda la seguridad de los individuos y de nuestro pa\u00eds.<\/p>\n<p><strong>Movilizar la inversi\u00f3n<\/strong><\/p>\n<p>Los pr\u00e9stamos p\u00fablicos a trav\u00e9s de la venta de bonos pueden proporcionar fondos sustanciales -y econ\u00f3micos- debido a la capacidad de la Reserva Federal para comprar bonos de infraestructura p\u00fablica a tasas bajas. Los bancos con fines p\u00fablicos, las cooperativas de cr\u00e9dito y los fondos de inversi\u00f3n y pr\u00e9stamos pueden proporcionar recursos financieros m\u00e1s descentralizados, especialmente para proyectos de menor escala y basados \u200b\u200ben la comunidad. Si es necesario, la Reserva Federal podr\u00eda comprar bonos de infraestructura, tal como lo hizo con los valores del Tesoro en 1940 para financiar el esfuerzo de guerra.<\/p>\n<p>Asimismo, el GND establecer\u00e1 un programa de bonos sobre el clima, como los bonos de guerra de la Segunda Guerra Mundial. Estos deben ser una buena inversi\u00f3n para las personas, en particular como una alternativa a los planes de pensiones hoy destruidos o amenazados. Si vamos a subsidiar la inversi\u00f3n en energ\u00eda, los beneficios deber\u00edan ir primero -y ante todo- no al 1%, sino a los ciudadanos comunes que puedan usarlos para aumentar su seguridad econ\u00f3mica y sus ahorros para la jubilaci\u00f3n.<\/p>\n<p><strong>Apoyar y financiar un Global Green New Deal<\/strong><\/p>\n<p>La realizaci\u00f3n de los objetivos del GND requiere una cooperaci\u00f3n global. Los gobiernos deben trabajar juntos para crear un marco global que respalde los empleos y el desarrollo respetuosos con el clima, lo que se ha denominado un &#8220;Nuevo Acuerdo Verde Global&#8221;. Eso requiere que el mundo abandone el neoliberalismo y adopte una nueva estrategia que ponga en funcionamiento los recursos humanos del mundo, dando respuesta a la acuciante necesidad de una transformaci\u00f3n econ\u00f3mica que reduzca radicalmente las emisiones de Gas de Efecto Invernadero (GEI).<\/p>\n<p>Es necesario un fondo de inversi\u00f3n global para la protecci\u00f3n del clima, a una escala que movilice los recursos humanos y materiales subutilizados en todo el mundo. En lugar de luchar entre s\u00ed por empleos que protegen el clima, los trabajadores de diferentes pa\u00edses podr\u00edan beneficiarse de las pol\u00edticas nacionales y los acuerdos internacionales que alienten a los pa\u00edses a cooperar para compartir tecnolog\u00edas verdes y expandir la producci\u00f3n para la protecci\u00f3n del clima. Los acuerdos internacionales legalmente vinculantes deben eliminar y prohibir el uso de combustibles f\u00f3siles en todo el mundo. Tanto la protecci\u00f3n del clima como la cooperaci\u00f3n econ\u00f3mica requieren, en \u00faltima instancia, la desmilitarizaci\u00f3n y pol\u00edticas de seguridad comunes a nivel mundial.<\/p>\n<p>La globalizaci\u00f3n, el neoliberalismo y los acuerdos de libre comercio han enfrentado a los trabajadores del mundo en una lucha por empleos que protegen el clima. El GND no enfrentar\u00e1 a trabajadores con trabajadores y se opondr\u00e1, tanto a la escalada de guerras comerciales, como a la utop\u00eda de libre comercio del neoliberalismo. En su lugar, buscar\u00e1 un comercio administrado conjuntamente que aliente a todos los pa\u00edses a desarrollar sus industrias y tecnolog\u00edas de protecci\u00f3n del clima lo m\u00e1s r\u00e1pido posible, al tiempo que permitir\u00e1 que los beneficios se compartan de una manera que proteja a los trabajadores tanto en los pa\u00edses en desarrollo como en los pa\u00edses desarrollados o, lo que es lo mismo, al planeta en su conjunto<\/p>\n<p><strong>Conclusi\u00f3n<\/strong><\/p>\n<p>El New Deal original de la d\u00e9cada de 1930 no fue un solo programa, o una norma legislativa. Represent\u00f3 toda una \u00e9poca de agitaci\u00f3n en la que las fuerzas en conflicto intentaron enfrentar una crisis devastadora y dar forma al futuro de la sociedad estadounidense. El New Deal era parte de un proceso de cambio social que inclu\u00eda la experimentaci\u00f3n a nivel estatal, regional y local, la organizaci\u00f3n entre los grupos de trabajadores, desempleados, rurales, urbanos, ancianos y otros grupos de base, as\u00ed como un animado debate sobre alternativas futuras que fueron mucho m\u00e1s all\u00e1 de las pol\u00edticas implementadas.<\/p>\n<p>En la pr\u00e1ctica, el GND involucrar\u00e1 de manera similar ideas y programas en disputa, impulsados, en alianza y oposici\u00f3n, por una amplia gama de grupos y organizaciones que apoyan el concepto amplio, pero no est\u00e1n de acuerdo con los detalles. Al igual que el New Deal original, el Green New Deal est\u00e1 tratando de hacer algo que nunca se ha hecho antes. Tendremos que aprender de la experiencia, y corregir los errores que inevitablemente cometeremos en el camino. Pero con esta estrategia podemos comenzar a caminar en la direcci\u00f3n correcta.<\/p>\n<div class=\"simple-footnotes\"><p class=\"notes\">Notes:<\/p><ol><li id=\"note-11184-1\"><\/span>Jeremy Brecher es historiador, cineasta, y cofundador de <em>Labor Network for Sustainability.<\/em> <a href=\"#return-note-11184-1\">&#8617;<\/a><\/li><\/ol><\/div>","protected":false},"excerpt":{"rendered":"<p>Galde 24, udaberria\/2019\/primavera.\u00a0Jeremy Brecher.-Green New Deal (GND) -presentado recientemente por la congresista Alexandra Ocasio-Cortez (D-NY) es la propuesta con la que el Partido Dem\u00f3crata pretende hacer frente a la crisis econ\u00f3mica y al cambio clim\u00e1tico. Notes:Jeremy Brecher es historiador, cineasta, y cofundador de Labor Network for Sustainability. &#8617;<\/p>\n","protected":false},"author":2,"featured_media":11191,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,5],"tags":[],"class_list":["post-11184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","category-politica","revista-galde-n24"],"_links":{"self":[{"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/posts\/11184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/comments?post=11184"}],"version-history":[{"count":0,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/posts\/11184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/media\/11191"}],"wp:attachment":[{"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/media?parent=11184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/categories?post=11184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.galde.eu\/eu\/wp-json\/wp\/v2\/tags?post=11184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}