{"id":8034,"date":"2017-11-02T12:32:18","date_gmt":"2017-11-02T11:32:18","guid":{"rendered":"https:\/\/www.galde.eu\/?p=8034"},"modified":"2025-10-23T19:35:42","modified_gmt":"2025-10-23T17:35:42","slug":"periodismo-critico-una-molestia-social","status":"publish","type":"post","link":"https:\/\/www.galde.eu\/es\/periodismo-critico-una-molestia-social\/","title":{"rendered":"Periodismo cr\u00edtico, una molestia social"},"content":{"rendered":"<div id=\"attachment_8035\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2017\/11\/1-0-uRNA-e1510247514408.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8035\" class=\"size-full wp-image-8035 colorbox-8034\" src=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2017\/11\/1-0-uRNA-e1510247514408.jpg\" alt=\"\" width=\"600\" height=\"400\" data-id=\"8035\" \/><\/a><p id=\"caption-attachment-8035\" class=\"wp-caption-text\">Policia Nacional intenta retirar una urna en la escuela Ramon Llull el 1 de octubre de 2017.<\/p><\/div>\n<p>Galde 19 (verano\/2017). Amparo Lasheras<a id=\"footnote-ref-1\" href=\"#footnote-1\">[1]<\/a>.<br \/>\nLa primera referencia al poder de la prensa la encontr\u00e9 cuando estudiaba bachillerato y, todav\u00eda adolescente, me debat\u00eda en la coyuntura existencial de saber qu\u00e9 quer\u00eda ser en la vida. Se trataba de un art\u00edculo que encontr\u00e9 al azar en un antiguo ejemplar de <em>Selecciones de Reader\u00b4s Digest<\/em>, una revista estadounidense, de corte conservador y anticomunista, que comenz\u00f3 a editarse en el Estado espa\u00f1ol en 1940. Lo descubr\u00ed en una especie de armario inservible donde mi familia hab\u00eda guardado discos del viejo gram\u00f3fono, prensa republicana, revistas y novelas ilustradas de los a\u00f1os 20 con obras de Gorki, Malraux, Stevenson, Dickens o Chejov, cuadernos de cultura popular editados por los anarquistas entre 1930 y 1933, algunas obras de Conan Doyle, Julio Verne o Agatha Christie, publicadas en 1940, y unos pocos n\u00fameros de <em>Selecciones<\/em> de la d\u00e9cada de los 50. El reportaje al que me refiero, titulado \u00abEl Cuarto Poder\u00bb, analizaba la influencia de los peri\u00f3dicos brit\u00e1nicos en la opini\u00f3n p\u00fablica y c\u00f3mo desde 1702, a\u00f1o en que apareci\u00f3 la primera edici\u00f3n del <em>Daily Courant<\/em>, ten\u00edan su sede en la c\u00e9ntrica Fleet Street, hoy un lugar de obligado recorrido tur\u00edstico en Londres. La calle fue durante d\u00e9cadas un hervidero de periodistas al estilo de la novela negra, de noticias, rumores y exclusivas que iban y ven\u00edan de los pubs a las redacciones hasta que, en 1986, gobernando Margaret Thatcher, el magnate de la comunicaci\u00f3n Rupert Murdoch decidi\u00f3 trasladar parte de sus diarios y tabloides (<em>The Times<\/em>, <em>The Sun<\/em>, <em>News of the World<\/em>) al este de Londres, al barrio industrial de Wapping. Iniciaba as\u00ed, con las nuevas tecnolog\u00edas, una reconversi\u00f3n de la industria period\u00edstica que se sald\u00f3 con el despido de miles de trabajadores, la mayor\u00eda de ellos sindicados, lo que facilit\u00f3 la casi desaparici\u00f3n de la acci\u00f3n sindical en detrimento de los derechos laborales de los periodistas y, tambi\u00e9n, el comienzo del desastre, del deterioro de la verdad y la honestidad en la informaci\u00f3n. El desmantelamiento de la conciliaci\u00f3n social y el estado de bienestar, iniciado por Ronald Reagan y Margaret Thatcher en los 80, iba a necesitar un \u201cnuevo\u201d ejercicio y concepto del periodismo, un frente medi\u00e1tico que controlase la opini\u00f3n p\u00fablica y no cuestionase las pol\u00edticas neoliberales que se aplicar\u00edan en el futuro.<\/p>\n<p>El art\u00edculo que menciono al principio, escrito en plena Guerra Fr\u00eda, explicaba el importante papel de la prensa en la constituci\u00f3n del \u201cmundo libre\u201d, construido al finalizar la II Guerra Mundial. Es cierto que el reportaje se somet\u00eda a las simpat\u00edas ideol\u00f3gicas de EEUU y arremet\u00eda con la realidad de los pa\u00edses socialistas pero, al menos, en la pr\u00e1ctica del periodismo, todav\u00eda defend\u00eda, aunque fuese en voz muy baja, la objetividad de la informaci\u00f3n, siempre necesaria para ofrecer a la poblaci\u00f3n un relato de los hechos lo m\u00e1s cercano a la verdad. Bajo esa idea, el periodista se convert\u00eda en notario de la realidad y, por lo tanto, la responsabilidad de su oficio deber\u00eda exigirle la pr\u00e1ctica de una rigurosa \u00e9tica consigo mismo y con la sociedad. Hoy, en la era de lo que llaman la postverdad, donde la manipulaci\u00f3n de un titular y la mentira r\u00e1pida de un mensaje se consideran verdades inapelables, en los grandes emporios de la comunicaci\u00f3n y tambi\u00e9n en los medios p\u00fablicos e incluso en las redes sociales, la \u00e9tica y la idea de una actitud de responsabilidad en el oficio de informar o escribir carecen de valor, se consideran irrelevantes. En general y salvo honrosas excepciones de proyectos independientes, comunitarios o de algunos intr\u00e9pidos <em>free-lances<\/em>, han sido suplantadas por la censura que, bajo la presi\u00f3n a ser despedido, el periodista ejerce sobre s\u00ed mismo y por la disposici\u00f3n voluntaria y desideologizada de saber callar, del servilismo agradecido ante los intereses de quien paga o gobierna. En lugar de reflejar la verdad de lo que ocurre, las grandes empresas de la comunicaci\u00f3n, creadas en el m\u00e1s genuino modelo ultraliberal y globalizado del capitalismo, han logrado que el periodismo pierda sus principios, doblegue a sus trabajadores con una precariedad abusiva, con sueldos de verg\u00fcenza y se convierta en una industria de fabricar noticias en cadena y corrientes de opini\u00f3n al servicio de los intereses econ\u00f3micos y pol\u00edticos del poder. En realidad, en el siglo XXI, estos grupos de comunicaci\u00f3n han desprovisto al oficio de informar de cr\u00edtica, denuncia y libertad ideol\u00f3gica. En las estrategias pol\u00edticas del sistema se ha constituido y se utiliza al periodismo como un importante y combativo frente para la alienaci\u00f3n colectiva de una \u201cciudadan\u00eda aturdida\u201d, propagando la incultura del populismo m\u00e1s \u201cfascistoide\u201d y, de una manera subliminal, el miedo, la inseguridad, el conformismo, el consumismo y hasta la xenofobia, creando con ello una hegemon\u00eda y un pensamiento \u00fanico incapaz de cuestionar el sistema. Se ha quedado atrapado en la peor interpretaci\u00f3n de lo que, en el siglo XVIII, el pol\u00edtico conservador Edmund Burke bautiz\u00f3 como el Cuarto Poder.<\/p>\n<p>Si hici\u00e9semos un an\u00e1lisis del comportamiento de los actuales medios de comunicaci\u00f3n (peri\u00f3dicos, radios, televisiones e internet) en las tr\u00e1gicas consecuencias sociales de la crisis sist\u00e9mica del 2008, en las invasiones y el expolio de materias primas en el continente africano; los desastres del cambio clim\u00e1tico; las guerras geoestrat\u00e9gicas por la hegemon\u00eda en negocio del petr\u00f3leo; el avance del populismo fascista en Europa; las c\u00ednicas pol\u00edticas de la UE con los y las refugiadas; en el Brexit, la islamofobia; en el genocidio del pueblo palestino por parte de Israel; en las intervenciones militares de EEUU y la UE en Irak, Libia o Siria o en los atentados del DHAES en el continente europeo, se demostrar\u00eda, en cada una de estas realidades y en su conjunto, la enorme importancia de la fidelidad de los medios a la estrategia pol\u00edtica, social y econ\u00f3mica del sistema.<\/p>\n<p>Pero no hay que abarcar tanto, ni ir muy lejos. S\u00f3lo hay que situarse en la celebraci\u00f3n, el 1 de octubre, del refer\u00e9ndum de autodeterminaci\u00f3n de Catalunya y observar el beligerante comportamiento de la prensa espa\u00f1ola con el Govern, los movimientos sociales y, en definitiva con la voluntad del pueblo catal\u00e1n. Cadenas de televisi\u00f3n, radios y prensa escrita, pertenecientes a diferentes grupos econ\u00f3micos (Vocento, PRISA, COPE, Planeta, Tresmedia&#8230;) se han unido en una misma agenda ideol\u00f3gica contra el derecho a decidir y la independencia de Catalunya. La convergencia del Gobierno del PP, con el PSOE y Ciudadanos, en la idea \u00fanica de la legalidad constitucional y de la unidad territorial y en la aplicaci\u00f3n del art\u00edculo 155, ha sido el buque insignia del mensaje y las manipulaciones que se han trasmitido a la sociedad a trav\u00e9s de informaciones de toda condici\u00f3n: entrevistas, programas, art\u00edculos de opini\u00f3n, editoriales, declaraciones, tertulias, debates&#8230; Las voces y razones discrepantes se han relegado o ignorado; las brutales actuaciones policiales contra personas que solo quer\u00edan ejercer su derecho a votar con libertad se han minimizado hasta justificarlas, apelando a la \u201cviolencia leg\u00edtima del Estado\u201d, teorizada y defendida por el fil\u00f3sofo alem\u00e1n Max Weber.<\/p>\n<p>Aqu\u00ed, entrar\u00eda en debate la libertad de prensa como instrumento del derecho a la libertad de expresi\u00f3n y la pregunta ser\u00eda \u00bfexiste esa libertad? La respuesta ser\u00eda categ\u00f3rica, no. Y aunque conviene recordar el cierre, en Euskal Herria, de <em>Egin<\/em> y <em>Egunkaria<\/em> (1988 y 2003) y, en Catalunya, hace pocas semanas, un semanario local (El Vallenc), adem\u00e1s de las p\u00e1ginas web del Referendum, de la Asamblea Catalana, de Omnium y la del propio Govern de la Generalitat, la libertad de prensa no est\u00e1 da\u00f1ada por una censura dictatorial, por leyes fascistas como las que se establecieron en Italia, Alemania, Espa\u00f1a o Argentina en el siglo pasado y que vulneraban la libertad de expresi\u00f3n y de informaci\u00f3n, no. Hoy, en 2017, para violar esos derechos se utilizan m\u00e9todos y proyectos m\u00e1s sofisticados y unidos a la imposici\u00f3n \u201cdemocr\u00e1tica\u201d de una ideolog\u00eda determinada y un pensamiento \u00fanico. Josep Ramoneda, periodista y fil\u00f3sofo catal\u00e1n, en su libro <em>La izquierda necesaria<\/em>, editado en 2012, afirmaba que \u201cla pol\u00edtica institucional cada vez est\u00e1 m\u00e1s desconectada de la sociedad y m\u00e1s conectada con unas \u00e9lites cerradas que solo se escuchan a s\u00ed mismas\u201d. \u201cY as\u00ed \u2013explicaba- se va avanzando por la senda que marca la econom\u00eda\u201d. \u201c\u00bfQui\u00e9n es esta econom\u00eda que todos tenemos que obedecer? Un ente compuesto, formado \u2013respond\u00eda- por los que tienen poder econ\u00f3mico y lo usan para influir en beneficio de sus intereses; un sinf\u00edn de expertos rendidos al dinero que en esta crisis han puesto en evidencia a los m\u00e1s famosos departamentos universitarios y escuelas de negocios; unos tecn\u00f3cratas con viaje de ida y vuelta entre el capital y la pol\u00edtica; y unos conversos que creen que solo de pan vive el hombre. En este contexto, \u00bfd\u00f3nde est\u00e1 la discusi\u00f3n sobre la sociedad que queremos?\u201d. En ninguna parte. Ese \u201cente\u201d al que se refiere J. Ramoneda, que ha estructurado con todas las herramientas posibles (ideol\u00f3gicas, t\u00e9cnicas y humanas), el control de la prensa y los medios de comunicaci\u00f3n para moldear y consolidar el car\u00e1cter social de un mundo donde pensar, transformar, desterrar la desigualdad y recuperar la libertad colectiva, supone \u201cuna molestia social\u201d, como revel\u00f3 Charles Chaplin, en el film de 1952, <em>Un Rey en Nueva York<\/em>, pel\u00edcula prohibida en EEUU durante 21 a\u00f1os.<\/p>\n<ul>\n<li id=\"footnote-1\">Periodista.<a href=\"#footnote-ref-1\">\u2191<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Galde 19 (verano\/2017). Amparo Lasheras[1]. La primera referencia al poder de la prensa la encontr\u00e9 cuando estudiaba bachillerato y, todav\u00eda adolescente, me debat\u00eda en la coyuntura existencial de saber qu\u00e9 quer\u00eda ser en la vida. Se trataba de un art\u00edculo que encontr\u00e9 al azar en un antiguo ejemplar de Selecciones de Reader\u00b4s Digest, una revista [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8036,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,5],"tags":[],"class_list":["post-8034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossier","category-politica","revista-galde-n19"],"_links":{"self":[{"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/posts\/8034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/comments?post=8034"}],"version-history":[{"count":1,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/posts\/8034\/revisions"}],"predecessor-version":[{"id":19252,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/posts\/8034\/revisions\/19252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/media\/8036"}],"wp:attachment":[{"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/media?parent=8034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/categories?post=8034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/tags?post=8034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}