{"id":12157,"date":"2020-03-26T19:48:21","date_gmt":"2020-03-26T18:48:21","guid":{"rendered":"https:\/\/www.galde.eu\/?p=12157"},"modified":"2020-03-30T10:27:24","modified_gmt":"2020-03-30T08:27:24","slug":"entrevista-tere-maldonado-bego-zugadi-feministalde","status":"publish","type":"post","link":"https:\/\/www.galde.eu\/es\/entrevista-tere-maldonado-bego-zugadi-feministalde\/","title":{"rendered":"Entrevista a Tere Maldonado y Bego Zugadi, de FeministAlde"},"content":{"rendered":"<p><a href=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2020\/03\/feministalde600x200-copia.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12165 colorbox-12157\" src=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2020\/03\/feministalde600x200-copia.jpeg\" alt=\"\" width=\"580\" height=\"192\" data-id=\"12165\" srcset=\"https:\/\/www.galde.eu\/wp-content\/uploads\/2020\/03\/feministalde600x200-copia.jpeg 580w, https:\/\/www.galde.eu\/wp-content\/uploads\/2020\/03\/feministalde600x200-copia-300x99.jpeg 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #ff0000;\"><br \/>\nV JORNADAS FEMINISTAS DE EUSKAL HERRIA<\/span><\/h3>\n<h3 style=\"text-align: center;\"><span style=\"color: #ff0000;\">\u00abLas jornadas son un escaparate de lo que los grupos feministas estamos haciendo\u201d<\/span><\/h3>\n<p>Galde 28, udaberria\/2020\/primavera. Elo Mayo entrevista a Tere Maldonado y Bego Zugadi, integrantes de <a href=\"https:\/\/twitter.com\/feministalde\" target=\"_blank\" rel=\"noopener noreferrer\">FeministAlde<\/a><strong>,<\/strong> un colectivo feminista, anticapitalista e internacionalista de Bilbao, compuesto por mujeres de diferentes edades; lesbianas, heteros y bisexuales, con diferentes circunstancias funcionales, mayoritariamente de Euskal Herria, aunque algunas tienen otros or\u00edgenes culturales, que \u201ccreemos que el feminismo es una herramienta fundamental para transformar la sociedad\u201d.<\/p>\n<p><strong>\u00bfHasta qu\u00e9 punto los temas que m\u00e1s han \u201csonado\u201d en las Jornadas Feministas son realmente nuevos en el feminismo vasco?<\/strong><\/p>\n<p>El tema de las mujeres racializadas es nuevo en unas jornadas, pero no as\u00ed en el feminismo vasco. Desde las jornadas anteriores, realizadas hace diez a\u00f1os en Portugalete, hasta hoy los temas de las racializadas y la decolonialidad han ido cogiendo mucha fuerza, desde que algunos grupos trajeron a Ochy Curiel, a Yuderkis Espinosa o a Rita Segato a dar charlas, de modo que el mensaje de la decolonialidad ya estaba lanzado y lo que ha sido novedoso es abordarlo en unas jornadas y hacerlo adem\u00e1s en una mesa central\u2026<\/p>\n<p>Otros temas que se han tratado no son nuevos, por ejemplo, el transfeminismo ha estado presente en el movimiento desde las jornadas estatales de C\u00f3rdoba en el 99 y adquiri\u00f3 carta de naturaleza en las de Granada diez a\u00f1os despu\u00e9s. En el feminismo vasco es ahora cuando se ha tratado en unas jornadas de una manera m\u00e1s \u201cnormalizada\u201d, pero irrumpi\u00f3 antes en el movimiento, al menos hace una d\u00e9cada, lo que pasa es que durante bastante tiempo fue un an\u00e1lisis y un lenguaje asumidos por una minor\u00eda en el movimiento feminista, pero ahora est\u00e1 a la orden del d\u00eda hablar de los cuerpos, las cuerpas y el g\u00e9nero fluido, es un lenguaje que utilizamos cada vez m\u00e1s todas, lo que no quiere decir que todas estemos de acuerdo en todo lo que se dice\u2026<\/p>\n<p><strong>Vosotras participasteis durante las jornadas en un debate sobre prostituci\u00f3n con mujeres de Medeak, AMAR y Lanbroa, en el que se logr\u00f3 algo que cada vez resulta m\u00e1s dif\u00edcil de hacer en otros lugares: sentar a feministas con posiciones antag\u00f3nicas sobre la prostituci\u00f3n\/trabajo sexual para que dialoguen y lleguen a algunos acuerdos b\u00e1sicos.<\/strong><\/p>\n<p>Nosotras consideramos que entre las posiciones m\u00e1s extremas a la hora de abordar la prostituci\u00f3n -las abolicionistas intransigentes por un lado, y las pro derechos que trivializan la prostituci\u00f3n consider\u00e1ndola un \u201ctrabajo como cualquiera\u201d por otro- hay muchos matices y colores; nosotras quer\u00edamos dar voz a esos colores, pero tambi\u00e9n decir que hab\u00eda que terminar con esa l\u00f3gica de \u201cme compras todo el discurso o no te acepto nada\u201d, que est\u00e1bamos hartas de los tintes que algunas abolicionistas le dan a la discusi\u00f3n, que parece un debate de teolog\u00eda m\u00e1s que de pol\u00edtica\u2026 Estas eran nuestras motivaciones b\u00e1sicas, porque quer\u00edamos salir al paso de lo que ocurre en otros lugares del Estado, donde es imposible sentarse a dialogar y las discusiones son desgarradoras; adem\u00e1s, el debate ven\u00eda estando un poco aplacado pero en los \u00faltimos meses, justo en el momento de mayor auge del movimiento feminista, volvi\u00f3 a resurgir un tema que nos divide y nos desgarra\u2026<\/p>\n<p>Sobre lo que pas\u00f3 en las jornadas, es de justicia mencionar que las compa\u00f1eras de Lanbroa, que representan la posici\u00f3n abolicionista, hicieron el esfuerzo de sentarse con nosotras y mantener un buen tono de discusi\u00f3n. Nosotras cuestionamos las dos posturas extremas, pero al mismo tiempo, rescatamos la idea de que ambas tienen matices aceptables y que no todo lo que dicen unas y otras es incompatible, a veces las posiciones simplemente no se tocan porque est\u00e1n hablando sobre la prostituci\u00f3n a niveles distintos. La sala estuvo abarrotada y hubo muchas intervenciones, se agradeci\u00f3 la oportunidad de poder hablar con tranquilidad sobre el tema y salimos contentas\u2026 El l\u00edo que se organiz\u00f3 despu\u00e9s en las redes, a partir de la cr\u00f3nica del debate que hizo Andrea Momoitio, de Pikara Magazine, tiene que ver con el hecho de que las redes tienen vida propia, permiten que aparezcan los planteamientos m\u00e1s intransigentes que convierten en dogma de fe la condena de la prostituci\u00f3n\u2026<\/p>\n<p><strong>\u00bfEchasteis en falta algunos temas que hubierais deseado ver planteados en las jornadas feministas?<\/strong><\/p>\n<p>S\u00ed, hay un debate que estaba claro que, si no lo organiz\u00e1bamos nosotras, no iba a salir: el de la laicidad. Es evidente que esta es una preocupaci\u00f3n bastante ajena al Movimiento Feminista de Euskal Herria y que no iba a estar presente en unas jornadas que las pensamos como un escaparate de lo que los grupos feministas estamos reflexionando, proponiendo o haciendo. Ten\u00edamos claro que no quer\u00edamos unas jornadas en las que fulanita o menganita del star system feminista vinieran a hablar, sino m\u00e1s bien una ocasi\u00f3n para abordar los temas que trabajamos en el movimiento feminista, porque eran unas jornadas del movimiento feminista organizado y los grupos est\u00e1n trabajando en lo que est\u00e1n trabajando.<\/p>\n<p>Por otro lado, las jornadas que hemos organizado cada d\u00e9cada tienen mucho de autoafirmaci\u00f3n muy emocional, de conocernos y ponernos caras entre las integrantes de los grupos feministas, entre las mayores y las j\u00f3venes. Son un escaparate donde se muestra lo que se est\u00e1 haciendo, pero es una quimera esperar que haya debate en una sala inmensa con 3 mil mujeres, el verdadero debate se hace despu\u00e9s de que terminan las jornadas, algunos hilos ah\u00ed se quedan porque nadie recoge lo planteado y otros tienen eco y se profundizan en los a\u00f1os siguientes; as\u00ed avanzamos\u2026 Y una nota de alegr\u00eda y optimismo: estuvimos muchos a\u00f1os con la preocupaci\u00f3n de que no hab\u00eda relevo, ahora ya est\u00e1 claro que esto no es un problema.<\/p>","protected":false},"excerpt":{"rendered":"<p>Galde 28, udaberria\/2020\/primavera. Elo Mayo entrevista a Tere Maldonado y Bego Zugadi, integrantes de FeministAlde, un colectivo feminista, anticapitalista e internacionalista de Bilbao, compuesto por mujeres de diferentes edades; lesbianas, heteros y bisexuales, con diferentes circunstancias funcionales, mayoritariamente de Euskal Herria, aunque algunas tienen otros or\u00edgenes culturales, que \u201ccreemos que el feminismo es una herramienta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12166,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-12157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","revista-galde-n28"],"_links":{"self":[{"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/posts\/12157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/comments?post=12157"}],"version-history":[{"count":0,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/posts\/12157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/media\/12166"}],"wp:attachment":[{"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/media?parent=12157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/categories?post=12157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.galde.eu\/es\/wp-json\/wp\/v2\/tags?post=12157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}